{"id":14,"count":2,"description":"","link":"https:\/\/designweekmexico.com\/en\/categoria\/diseno-social\/","name":"Socially Responsible Design","slug":"diseno-social","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dise\u00f1o Socialmente Responsable Archivos - Design Week Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/designweekmexico.com\/en\/categoria\/diseno-social\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dise\u00f1o Socialmente Responsable Archivos - Design Week Mexico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/designweekmexico.com\/en\/categoria\/diseno-social\/\" \/>\n<meta property=\"og:site_name\" content=\"Design Week Mexico\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@designweekmex\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/categoria\\\/diseno-social\\\/\",\"url\":\"https:\\\/\\\/designweekmexico.com\\\/categoria\\\/diseno-social\\\/\",\"name\":\"Dise\u00f1o Socialmente Responsable Archivos - Design Week Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/categoria\\\/diseno-social\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/categoria\\\/diseno-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/designweekmexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dise\u00f1o Socialmente Responsable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#website\",\"url\":\"https:\\\/\\\/designweekmexico.com\\\/\",\"name\":\"Design Week Mexico\",\"description\":\"Dise\u00f1ando el futuro...\",\"publisher\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/designweekmexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#organization\",\"name\":\"Design Week Mexico\",\"url\":\"https:\\\/\\\/designweekmexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/designweekmexico.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Asset-58-70eae4-3141d7.svg\",\"contentUrl\":\"https:\\\/\\\/designweekmexico.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Asset-58-70eae4-3141d7.svg\",\"width\":1741,\"height\":103,\"caption\":\"Design Week Mexico\"},\"image\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/designweekmex\",\"https:\\\/\\\/x.com\\\/designweekmex\",\"https:\\\/\\\/www.instagram.com\\\/designweekmex\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/designweekmexico\",\"https:\\\/\\\/vimeo.com\\\/designweekmexico\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/designweekmx\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dise\u00f1o Socialmente Responsable Archivos - Design Week Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/designweekmexico.com\/en\/categoria\/diseno-social\/","og_locale":"en_US","og_type":"article","og_title":"Dise\u00f1o Socialmente Responsable Archivos - Design Week Mexico","og_url":"https:\/\/designweekmexico.com\/en\/categoria\/diseno-social\/","og_site_name":"Design Week Mexico","twitter_card":"summary_large_image","twitter_site":"@designweekmex","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/designweekmexico.com\/categoria\/diseno-social\/","url":"https:\/\/designweekmexico.com\/categoria\/diseno-social\/","name":"Dise\u00f1o Socialmente Responsable Archivos - Design Week Mexico","isPartOf":{"@id":"https:\/\/designweekmexico.com\/#website"},"breadcrumb":{"@id":"https:\/\/designweekmexico.com\/categoria\/diseno-social\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/designweekmexico.com\/categoria\/diseno-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/designweekmexico.com\/"},{"@type":"ListItem","position":2,"name":"Dise\u00f1o Socialmente Responsable"}]},{"@type":"WebSite","@id":"https:\/\/designweekmexico.com\/#website","url":"https:\/\/designweekmexico.com\/","name":"Design Week Mexico","description":"Dise\u00f1ando el futuro...","publisher":{"@id":"https:\/\/designweekmexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/designweekmexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/designweekmexico.com\/#organization","name":"Design Week Mexico","url":"https:\/\/designweekmexico.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/designweekmexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/designweekmexico.com\/wp-content\/uploads\/2026\/04\/Asset-58-70eae4-3141d7.svg","contentUrl":"https:\/\/designweekmexico.com\/wp-content\/uploads\/2026\/04\/Asset-58-70eae4-3141d7.svg","width":1741,"height":103,"caption":"Design Week Mexico"},"image":{"@id":"https:\/\/designweekmexico.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/designweekmex","https:\/\/x.com\/designweekmex","https:\/\/www.instagram.com\/designweekmex\/","https:\/\/www.youtube.com\/user\/designweekmexico","https:\/\/vimeo.com\/designweekmexico","https:\/\/www.linkedin.com\/company\/designweekmx\/"]}]}},"_links":{"self":[{"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/categories\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/posts?categories=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}