{"id":158,"count":9,"description":"La d\u00e9cimo s\u00e9ptima edici\u00f3n de Design Week Mexico se presenta bajo el lema \u201cDise\u00f1ado en M\u00e9xico\u201d. Este a\u00f1o, el enfoque celebra la creatividad, identidad y talento que definen al dise\u00f1o hecho en nuestro pa\u00eds. A trav\u00e9s de exposiciones, instalaciones y programas especiales, el evento resalta la riqueza de materiales, t\u00e9cnicas y visiones que emergen desde lo local hacia lo global. Design Week Mexico 2025 invita a reflexionar sobre lo que significa dise\u00f1ar desde M\u00e9xico, reconociendo tanto la tradici\u00f3n como la innovaci\u00f3n que dan forma a nuestro presente y futuro creativo.","link":"https:\/\/designweekmexico.com\/en\/categoria\/programa-2025\/","name":"DWM25","slug":"programa-2025","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DWM25 Archivos - Design Week Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/designweekmexico.com\/en\/categoria\/programa-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DWM25 Archivos - Design Week Mexico\" \/>\n<meta property=\"og:description\" content=\"La d\u00e9cimo s\u00e9ptima edici\u00f3n de Design Week Mexico se presenta bajo el lema \u201cDise\u00f1ado en M\u00e9xico\u201d. Este a\u00f1o, el enfoque celebra la creatividad, identidad y talento que definen al dise\u00f1o hecho en nuestro pa\u00eds. A trav\u00e9s de exposiciones, instalaciones y programas especiales, el evento resalta la riqueza de materiales, t\u00e9cnicas y visiones que emergen desde lo local hacia lo global. Design Week Mexico 2025 invita a reflexionar sobre lo que significa dise\u00f1ar desde M\u00e9xico, reconociendo tanto la tradici\u00f3n como la innovaci\u00f3n que dan forma a nuestro presente y futuro creativo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/designweekmexico.com\/en\/categoria\/programa-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Design Week Mexico\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@designweekmex\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/categoria\\\/programa-2025\\\/\",\"url\":\"https:\\\/\\\/designweekmexico.com\\\/categoria\\\/programa-2025\\\/\",\"name\":\"DWM25 Archivos - Design Week Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/categoria\\\/programa-2025\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/categoria\\\/programa-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/designweekmexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DWM25\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#website\",\"url\":\"https:\\\/\\\/designweekmexico.com\\\/\",\"name\":\"Design Week Mexico\",\"description\":\"Dise\u00f1ando el futuro...\",\"publisher\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/designweekmexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#organization\",\"name\":\"Design Week Mexico\",\"url\":\"https:\\\/\\\/designweekmexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/designweekmexico.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Asset-58-70eae4-3141d7.svg\",\"contentUrl\":\"https:\\\/\\\/designweekmexico.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Asset-58-70eae4-3141d7.svg\",\"width\":1741,\"height\":103,\"caption\":\"Design Week Mexico\"},\"image\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/designweekmex\",\"https:\\\/\\\/x.com\\\/designweekmex\",\"https:\\\/\\\/www.instagram.com\\\/designweekmex\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/designweekmexico\",\"https:\\\/\\\/vimeo.com\\\/designweekmexico\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/designweekmx\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DWM25 Archivos - Design Week Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/designweekmexico.com\/en\/categoria\/programa-2025\/","og_locale":"en_US","og_type":"article","og_title":"DWM25 Archivos - Design Week Mexico","og_description":"La d\u00e9cimo s\u00e9ptima edici\u00f3n de Design Week Mexico se presenta bajo el lema \u201cDise\u00f1ado en M\u00e9xico\u201d. Este a\u00f1o, el enfoque celebra la creatividad, identidad y talento que definen al dise\u00f1o hecho en nuestro pa\u00eds. A trav\u00e9s de exposiciones, instalaciones y programas especiales, el evento resalta la riqueza de materiales, t\u00e9cnicas y visiones que emergen desde lo local hacia lo global. Design Week Mexico 2025 invita a reflexionar sobre lo que significa dise\u00f1ar desde M\u00e9xico, reconociendo tanto la tradici\u00f3n como la innovaci\u00f3n que dan forma a nuestro presente y futuro creativo.","og_url":"https:\/\/designweekmexico.com\/en\/categoria\/programa-2025\/","og_site_name":"Design Week Mexico","twitter_card":"summary_large_image","twitter_site":"@designweekmex","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/designweekmexico.com\/categoria\/programa-2025\/","url":"https:\/\/designweekmexico.com\/categoria\/programa-2025\/","name":"DWM25 Archivos - Design Week Mexico","isPartOf":{"@id":"https:\/\/designweekmexico.com\/#website"},"breadcrumb":{"@id":"https:\/\/designweekmexico.com\/categoria\/programa-2025\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/designweekmexico.com\/categoria\/programa-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/designweekmexico.com\/"},{"@type":"ListItem","position":2,"name":"DWM25"}]},{"@type":"WebSite","@id":"https:\/\/designweekmexico.com\/#website","url":"https:\/\/designweekmexico.com\/","name":"Design Week Mexico","description":"Dise\u00f1ando el futuro...","publisher":{"@id":"https:\/\/designweekmexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/designweekmexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/designweekmexico.com\/#organization","name":"Design Week Mexico","url":"https:\/\/designweekmexico.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/designweekmexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/designweekmexico.com\/wp-content\/uploads\/2026\/04\/Asset-58-70eae4-3141d7.svg","contentUrl":"https:\/\/designweekmexico.com\/wp-content\/uploads\/2026\/04\/Asset-58-70eae4-3141d7.svg","width":1741,"height":103,"caption":"Design Week Mexico"},"image":{"@id":"https:\/\/designweekmexico.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/designweekmex","https:\/\/x.com\/designweekmex","https:\/\/www.instagram.com\/designweekmex\/","https:\/\/www.youtube.com\/user\/designweekmexico","https:\/\/vimeo.com\/designweekmexico","https:\/\/www.linkedin.com\/company\/designweekmx\/"]}]}},"_links":{"self":[{"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/categories\/158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/posts?categories=158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}