{"id":4325,"date":"2021-09-23T13:09:42","date_gmt":"2021-09-23T18:09:42","guid":{"rendered":"https:\/\/designweekmexico.com\/?p=4325"},"modified":"2023-07-18T12:47:42","modified_gmt":"2023-07-18T17:47:42","slug":"ine-21","status":"publish","type":"post","link":"https:\/\/designweekmexico.com\/en\/catalogo\/ine-21\/","title":{"rendered":"In\u00e9dito 2021"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Conoce todas las piezas de&nbsp;<strong>In\u00e9dito<\/strong>&nbsp;en las categor\u00edas: <strong><a href=\"https:\/\/designweekmexico.com\/catalogo\/in\/#edicion-limitada\">Edici\u00f3n Limitada,<\/a> <a href=\"https:\/\/designweekmexico.com\/catalogo\/in\/#profesional\">Professional<\/a><\/strong> and <strong><a href=\"https:\/\/designweekmexico.com\/catalogo\/in\/#universitario\">Universitario.<\/a><\/strong> Selecciona una categor\u00eda o una pieza para ver m\u00e1s.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/designweekmexico.com\/catalogo\/in\/#edicion-limitada\"><strong>Edici\u00f3n Limitada<\/strong><\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/designweekmexico.com\/catalogo\/in\/#profesional\"><strong>Professional<\/strong><\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/designweekmexico.com\/catalogo\/in\/#universitario\"><strong>Universitario<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-getwid-anchor\" id=\"edicion-limitada\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Edici\u00f3n Limitada<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Por primera vez, In\u00e9dito cuenta con una colecci\u00f3n de piezas limitadas de una selecci\u00f3n de dise\u00f1adores mexicanos.<\/p>\n\n\n\n<div style=\"width:100%\"><div class=\"wd_error\"><p><strong>There is no gallery selected or the gallery was deleted.<\/strong><\/p><\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-getwid-anchor\" id=\"profesional\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Professional<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Por primera vez, In\u00e9dito cuenta con una colecci\u00f3n de piezas limitadas de una selecci\u00f3n de dise\u00f1adores mexicanos.<\/p>\n\n\n\n<div style=\"width:100%\"><div class=\"wd_error\"><p><strong>There is no gallery selected or the gallery was deleted.<\/strong><\/p><\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-getwid-anchor\" id=\"universitario\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Universitario<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Por primera vez, In\u00e9dito cuenta con una colecci\u00f3n de piezas limitadas de una selecci\u00f3n de dise\u00f1adores mexicanos.<\/p>\n\n\n\n<div style=\"width:100%\"><div class=\"wd_error\"><p><strong>There is no gallery selected or the gallery was deleted.<\/strong><\/p><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Conoce todas las piezas de&nbsp;In\u00e9dito&nbsp;en las categor\u00edas: Edici\u00f3n Limitada, Profesional y Universitario. Selecciona una categor\u00eda o una pieza para ver m\u00e1s. Edici\u00f3n Limitada Por primera vez, In\u00e9dito cuenta con una colecci\u00f3n de piezas limitadas de una selecci\u00f3n de dise\u00f1adores mexicanos. Profesional Por primera vez, In\u00e9dito cuenta con una colecci\u00f3n de piezas limitadas de una selecci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[42],"tags":[],"class_list":["post-4325","post","type-post","status-publish","format-standard","hentry","category-catalogo"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In\u00e9dito 2021 - Design Week Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/designweekmexico.com\/en\/catalogo\/ine-21\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In\u00e9dito 2021 - Design Week Mexico\" \/>\n<meta property=\"og:description\" content=\"Conoce todas las piezas de&nbsp;In\u00e9dito&nbsp;en las categor\u00edas: Edici\u00f3n Limitada, Profesional y Universitario. Selecciona una categor\u00eda o una pieza para ver m\u00e1s. Edici\u00f3n Limitada Por primera vez, In\u00e9dito cuenta con una colecci\u00f3n de piezas limitadas de una selecci\u00f3n de dise\u00f1adores mexicanos. Profesional Por primera vez, In\u00e9dito cuenta con una colecci\u00f3n de piezas limitadas de una selecci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/designweekmexico.com\/en\/catalogo\/ine-21\/\" \/>\n<meta property=\"og:site_name\" content=\"Design Week Mexico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/designweekmex\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-23T18:09:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-18T17:47:42+00:00\" \/>\n<meta name=\"author\" content=\"Design Week Mexico\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@designweekmex\" \/>\n<meta name=\"twitter:site\" content=\"@designweekmex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Design Week Mexico\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/catalogo\\\/ine-21\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/catalogo\\\/ine-21\\\/\"},\"author\":{\"name\":\"Design Week Mexico\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#\\\/schema\\\/person\\\/0b5016c53aa584cccbd7f8988f8bdf42\"},\"headline\":\"In\u00e9dito 2021\",\"datePublished\":\"2021-09-23T18:09:42+00:00\",\"dateModified\":\"2023-07-18T17:47:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/catalogo\\\/ine-21\\\/\"},\"wordCount\":134,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#organization\"},\"articleSection\":[\"Cat\u00e1logo\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/designweekmexico.com\\\/catalogo\\\/ine-21\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/catalogo\\\/ine-21\\\/\",\"url\":\"https:\\\/\\\/designweekmexico.com\\\/catalogo\\\/ine-21\\\/\",\"name\":\"In\u00e9dito 2021 - Design Week Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#website\"},\"datePublished\":\"2021-09-23T18:09:42+00:00\",\"dateModified\":\"2023-07-18T17:47:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/catalogo\\\/ine-21\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/designweekmexico.com\\\/catalogo\\\/ine-21\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/catalogo\\\/ine-21\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/designweekmexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In\u00e9dito 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#website\",\"url\":\"https:\\\/\\\/designweekmexico.com\\\/\",\"name\":\"Design Week Mexico\",\"description\":\"Dise\u00f1ando el futuro...\",\"publisher\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/designweekmexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#organization\",\"name\":\"Design Week Mexico\",\"url\":\"https:\\\/\\\/designweekmexico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/designweekmexico.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Asset-58-70eae4-3141d7.svg\",\"contentUrl\":\"https:\\\/\\\/designweekmexico.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Asset-58-70eae4-3141d7.svg\",\"width\":1741,\"height\":103,\"caption\":\"Design Week Mexico\"},\"image\":{\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/designweekmex\",\"https:\\\/\\\/x.com\\\/designweekmex\",\"https:\\\/\\\/www.instagram.com\\\/designweekmex\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/designweekmexico\",\"https:\\\/\\\/vimeo.com\\\/designweekmexico\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/designweekmx\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/designweekmexico.com\\\/#\\\/schema\\\/person\\\/0b5016c53aa584cccbd7f8988f8bdf42\",\"name\":\"Design Week Mexico\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0830bfc50cafacf340fb14966c0f6cc5c88935cded635f38ae2ed050785fd609?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0830bfc50cafacf340fb14966c0f6cc5c88935cded635f38ae2ed050785fd609?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0830bfc50cafacf340fb14966c0f6cc5c88935cded635f38ae2ed050785fd609?s=96&d=mm&r=g\",\"caption\":\"Design Week Mexico\"},\"url\":\"https:\\\/\\\/designweekmexico.com\\\/en\\\/author\\\/designweekmexico\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In\u00e9dito 2021 - Design Week Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/designweekmexico.com\/en\/catalogo\/ine-21\/","og_locale":"en_US","og_type":"article","og_title":"In\u00e9dito 2021 - Design Week Mexico","og_description":"Conoce todas las piezas de&nbsp;In\u00e9dito&nbsp;en las categor\u00edas: Edici\u00f3n Limitada, Profesional y Universitario. Selecciona una categor\u00eda o una pieza para ver m\u00e1s. Edici\u00f3n Limitada Por primera vez, In\u00e9dito cuenta con una colecci\u00f3n de piezas limitadas de una selecci\u00f3n de dise\u00f1adores mexicanos. Profesional Por primera vez, In\u00e9dito cuenta con una colecci\u00f3n de piezas limitadas de una selecci\u00f3n [&hellip;]","og_url":"https:\/\/designweekmexico.com\/en\/catalogo\/ine-21\/","og_site_name":"Design Week Mexico","article_publisher":"https:\/\/www.facebook.com\/designweekmex","article_published_time":"2021-09-23T18:09:42+00:00","article_modified_time":"2023-07-18T17:47:42+00:00","author":"Design Week Mexico","twitter_card":"summary_large_image","twitter_creator":"@designweekmex","twitter_site":"@designweekmex","twitter_misc":{"Written by":"Design Week Mexico","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/designweekmexico.com\/catalogo\/ine-21\/#article","isPartOf":{"@id":"https:\/\/designweekmexico.com\/catalogo\/ine-21\/"},"author":{"name":"Design Week Mexico","@id":"https:\/\/designweekmexico.com\/#\/schema\/person\/0b5016c53aa584cccbd7f8988f8bdf42"},"headline":"In\u00e9dito 2021","datePublished":"2021-09-23T18:09:42+00:00","dateModified":"2023-07-18T17:47:42+00:00","mainEntityOfPage":{"@id":"https:\/\/designweekmexico.com\/catalogo\/ine-21\/"},"wordCount":134,"commentCount":0,"publisher":{"@id":"https:\/\/designweekmexico.com\/#organization"},"articleSection":["Cat\u00e1logo"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/designweekmexico.com\/catalogo\/ine-21\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/designweekmexico.com\/catalogo\/ine-21\/","url":"https:\/\/designweekmexico.com\/catalogo\/ine-21\/","name":"In\u00e9dito 2021 - Design Week Mexico","isPartOf":{"@id":"https:\/\/designweekmexico.com\/#website"},"datePublished":"2021-09-23T18:09:42+00:00","dateModified":"2023-07-18T17:47:42+00:00","breadcrumb":{"@id":"https:\/\/designweekmexico.com\/catalogo\/ine-21\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/designweekmexico.com\/catalogo\/ine-21\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/designweekmexico.com\/catalogo\/ine-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/designweekmexico.com\/"},{"@type":"ListItem","position":2,"name":"In\u00e9dito 2021"}]},{"@type":"WebSite","@id":"https:\/\/designweekmexico.com\/#website","url":"https:\/\/designweekmexico.com\/","name":"Design Week Mexico","description":"Dise\u00f1ando el futuro...","publisher":{"@id":"https:\/\/designweekmexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/designweekmexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/designweekmexico.com\/#organization","name":"Design Week Mexico","url":"https:\/\/designweekmexico.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/designweekmexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/designweekmexico.com\/wp-content\/uploads\/2026\/04\/Asset-58-70eae4-3141d7.svg","contentUrl":"https:\/\/designweekmexico.com\/wp-content\/uploads\/2026\/04\/Asset-58-70eae4-3141d7.svg","width":1741,"height":103,"caption":"Design Week Mexico"},"image":{"@id":"https:\/\/designweekmexico.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/designweekmex","https:\/\/x.com\/designweekmex","https:\/\/www.instagram.com\/designweekmex\/","https:\/\/www.youtube.com\/user\/designweekmexico","https:\/\/vimeo.com\/designweekmexico","https:\/\/www.linkedin.com\/company\/designweekmx\/"]},{"@type":"Person","@id":"https:\/\/designweekmexico.com\/#\/schema\/person\/0b5016c53aa584cccbd7f8988f8bdf42","name":"Design Week Mexico","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0830bfc50cafacf340fb14966c0f6cc5c88935cded635f38ae2ed050785fd609?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0830bfc50cafacf340fb14966c0f6cc5c88935cded635f38ae2ed050785fd609?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0830bfc50cafacf340fb14966c0f6cc5c88935cded635f38ae2ed050785fd609?s=96&d=mm&r=g","caption":"Design Week Mexico"},"url":"https:\/\/designweekmexico.com\/en\/author\/designweekmexico\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/posts\/4325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/comments?post=4325"}],"version-history":[{"count":0,"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/posts\/4325\/revisions"}],"wp:attachment":[{"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/media?parent=4325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/categories?post=4325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/designweekmexico.com\/en\/wp-json\/wp\/v2\/tags?post=4325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}